{"id":148,"date":"2025-10-13T08:29:13","date_gmt":"2025-10-13T08:29:13","guid":{"rendered":"https:\/\/norkeceramics.com\/?p=148"},"modified":"2026-04-30T06:00:20","modified_gmt":"2026-04-30T06:00:20","slug":"rohrformiger-piezoelektrischer-keramik-schwingungsfuhrer","status":"publish","type":"post","link":"https:\/\/norkeceramics.com\/de\/rohrformiger-piezoelektrischer-keramik-schwingungsfuhrer\/","title":{"rendered":"Rohrf\u00f6rmiger piezoelektrischer Keramik-Schwingungsf\u00fchrer"},"content":{"rendered":"<p>R\u00f6hrenf\u00f6rmige piezoelektrische Keramiken wandeln elektrische Energie und mechanische Schwingungen in kompakten Strukturen um. Das Verst\u00e4ndnis der Schwingungsrichtung hilft K\u00e4ufern, ihre Designabsichten bei der Beschaffung kundenspezifischer Keramikkomponenten klarer zu kommunizieren.<\/p>\n<h2>Wichtige Auswahlkriterien<\/h2>\n<ul>\n<li>Polarisationsrichtung und Elektrodenanordnung best\u00e4tigen<\/li>\n<li>Vibrationsmodus an Ger\u00e4tefunktion anpassen<\/li>\n<li>Pr\u00fcfen Sie die Anforderungen an Wandst\u00e4rke, Durchmesser und L\u00e4nge.<\/li>\n<li>Stellen Sie die elektrischen und mechanischen Bedingungen f\u00fcr die \u00dcberpr\u00fcfung bereit.<\/li>\n<\/ul>\n<h2>Wo es verwendet wird<\/h2>\n<ul>\n<li>Sensoren und Wandler<\/li>\n<li>Ultraschall- und Vibrationsger\u00e4te<\/li>\n<li>Pr\u00e4zisionselektronische Keramikbaugruppen<\/li>\n<li>Kundenspezifische rohrf\u00f6rmige Keramikkomponenten<\/li>\n<\/ul>\n<h2>K\u00e4uferhinweise<\/h2>\n<p>F\u00fcr Kaufentscheidungen sind neben der Bezeichnung der Keramik auch G\u00fcteklasse, Toleranz, Betriebstemperatur, Belastung, elektrische Anforderungen und Installationsumgebung von gr\u00f6\u00dfter Bedeutung. Die fr\u00fchzeitige Bereitstellung dieser Details erm\u00f6glicht es NORKE, ein realistisches Material und einen geeigneten Produktionsprozess zu empfehlen.<\/p>\n<h2>Bitten Sie NORKE um Unterst\u00fctzung.<\/h2>\n<p>Senden Sie uns Zeichnungen, Beispielfotos oder Anwendungsbeschreibungen, wenn Sie ein kundenspezifisches technisches Keramikbauteil ben\u00f6tigen. Wir pr\u00fcfen gerne die Herstellbarkeit, bevor wir Ihnen ein Angebot unterbreiten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein praktischer Leitfaden zur Schwingungsrichtung in rohrf\u00f6rmigen piezoelektrischen Keramiken und worauf K\u00e4ufer bei der Auswahl kundenspezifischer Keramikkomponenten achten sollten.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-148","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/posts\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":2,"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"predecessor-version":[{"id":6448,"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/posts\/148\/revisions\/6448"}],"wp:attachment":[{"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/norkeceramics.com\/de\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}